{"id":2572,"date":"2019-11-03T10:42:20","date_gmt":"2019-11-03T12:42:20","guid":{"rendered":"http:\/\/bvc-volei.org\/site\/?p=2572"},"modified":"2019-11-03T10:42:20","modified_gmt":"2019-11-03T12:42:20","slug":"sao-paulo-f-c-barueri-consegue-virada-historica-e-avanca-para-a-final-do-paulista-feminino-de-volei","status":"publish","type":"post","link":"https:\/\/bvc-volei.org\/site\/sao-paulo-f-c-barueri-consegue-virada-historica-e-avanca-para-a-final-do-paulista-feminino-de-volei\/","title":{"rendered":"S\u00e3o Paulo F.C\/Barueri consegue virada hist\u00f3rica e avan\u00e7a para a final do Paulista feminino de v\u00f4lei"},"content":{"rendered":"<p>Tricolor supera o favorito Sesi Bauru duas vezes no Gin\u00e1sio Panela de Press\u00e3o e ir\u00e1 decidir o Estadual contra Osasco Audax ou Pinheiros<\/p>\n<p>O S\u00e3o Paulo F.C\/Barueri conquistou uma virada hist\u00f3rica e avan\u00e7ou para a final do Campeonato Paulista feminino de v\u00f4lei. Em um confronto que terminou na madrugada deste domingo (3), o Tricolor superou o Sesi Bauru duas vezes na semifinal do Estadual, no Gin\u00e1sio Panela de Press\u00e3o, e alcan\u00e7ou a final da competi\u00e7\u00e3o, quando ir\u00e1 enfrentar o vencedor do duelo entre Osasco Audax e Pinheiros.<\/p>\n<p>Primeiro, o S\u00e3o Paulo F.C\/Barueri acabou com a invencibilidade do Bauru, primeiro colocado na fase de classifica\u00e7\u00e3o, vencendo por 3 sets a 0 (parciais de 25-19, 25-19 e25-20). Com a s\u00e9rie empatada em 1 a 1 (o Sesi Bauru venceu o jogo de ida em Barueri por 3 a 0), a decis\u00e3o foi para o Golden Set e mais uma vez o Tricolor se imp\u00f4s ao advers\u00e1rio, vencendo a parcial decisiva por 25-16. No total, o jogo teve 1h51min de dura\u00e7\u00e3o.<\/p>\n<p>O S\u00e3o Paulo F.C\/Barueri entrou muito concentrado desde o primeiro set. Consciente de que teria que vencer o Sesi Bauru duas vezes no mesmo dia, o Tricolor pisou no acelerador logo de cara. Com \u00f3timo aproveitamento da ponteira Maira, o Tricolor assumiu a dianteira no marcador a partir de 16 a 14 e n\u00e3o deu chance ao rival, fazendo 25-19.<\/p>\n<p>O time de Barueri aproveitou o descontrole do Sesi Bauru no segundo set, que foi cometendo muitos erros, especialmente no saque. Na parte final da parcial, abriu uma vantagem confort\u00e1vel de cinco pontos e fechou novamente por 25-19. No \u00faltimo set, o S\u00e3o Paulo F.C\/Barueri atropelou o rival, chegando a abrir 20\/13. O time chegou a permitir uma rea\u00e7\u00e3o, mas controlou os nervos e fechou em 25-20.<\/p>\n<p>O Golden Set come\u00e7ou na mesma toada dos anteriores, com o Tricolor mostrando um excelente aproveitamento ofensivo e aproveitando o incr\u00edvel n\u00famero de erros do Sesi Bauru. Por sinal, foi um erro da equipe da casa que deu a vit\u00f3ria por 25-16 e definiu a classifica\u00e7\u00e3o do S\u00e3o Paulo F.C\/Barueri para a final do Campeonato Paulista.<\/p>\n<p>Os destaques do Tricolor foram Maira e Lorenne, ambas com 19 pontos. Tainara aparece na sequ\u00eancia na lista de principais pontuadores do time, com 13 pontos nesta semifinal.<\/p>\n<p>\u201cN\u00f3s usamos a vantagem delas para ser a nossa vantagem. Hoje jogamos como um time. Cada vez que uma errava, a outra aparecia para consertar. Agora, vamos chegar para a final e n\u00e3o levar este resultado como um peso, pelo fato de termos eliminado o atual campe\u00e3o. Temos que tentar jogar soltas como fizemos aqui, a gente se divertiu jogando\u201d, afirmou a levantadora Juma.<\/p>\n<p>A ponteira Tainara tamb\u00e9m destacou a uni\u00e3o mostrada pela equipe em quadra nesta semifinal. \u201cEstivemos muito unidas neste jogo, nos mostramos focadas o tempo todo. A responsabilidade era toda delas, mas felizmente conseguimos nos superar. Fizemos um jogo excelente, colocar um 4 a 0 em uma equipe como o Bauru n\u00e3o \u00e9 f\u00e1cil. Agora, vamos para a final\u201d, afirmou.<\/p>\n<p>O S\u00e3o Paulo F.C\/Barueri jogou e venceu com Juma, Mayany, Tainara, Maira, Diana, Lorenne e Nyeme. Entraram durante o jogo Dani Terra, Kisy e Jacke.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<figure id=\"attachment_2558\" aria-describedby=\"caption-attachment-2558\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-2558\" src=\"http:\/\/bvc-volei.org\/site\/wp-content\/uploads\/2019\/10\/0606-1024x675.jpg\" alt=\"\" width=\"1024\" height=\"675\" srcset=\"https:\/\/bvc-volei.org\/site\/wp-content\/uploads\/2019\/10\/0606-1024x675.jpg 1024w, https:\/\/bvc-volei.org\/site\/wp-content\/uploads\/2019\/10\/0606-300x198.jpg 300w, https:\/\/bvc-volei.org\/site\/wp-content\/uploads\/2019\/10\/0606-768x506.jpg 768w, https:\/\/bvc-volei.org\/site\/wp-content\/uploads\/2019\/10\/0606-128x84.jpg 128w, https:\/\/bvc-volei.org\/site\/wp-content\/uploads\/2019\/10\/0606-32x21.jpg 32w, https:\/\/bvc-volei.org\/site\/wp-content\/uploads\/2019\/10\/0606-98x65.jpg 98w, https:\/\/bvc-volei.org\/site\/wp-content\/uploads\/2019\/10\/0606-600x396.jpg 600w, https:\/\/bvc-volei.org\/site\/wp-content\/uploads\/2019\/10\/0606.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-2558\" class=\"wp-caption-text\">Jos\u00e9 Roberto Guimar\u00e3es<br \/>cr\u00e9dito: Rubens Chiri\/S\u00e3o PauloFC.net<\/figcaption><\/figure>\n<p><strong>Jogos do S\u00e3o Paulo F.C\/Barueri no Paulista de v\u00f4lei<\/strong><\/p>\n<p><strong>Fase Classificat\u00f3ria<\/strong><\/p>\n<p>3\/9 \u2013\u00a0<strong>S\u00e3o Paulo F.C\/Barueri<\/strong>\u00a03 x 0 V\u00f4lei Valinhos (25-17, 25-21 e 25-21)<br \/>\nGin\u00e1sio Jos\u00e9 Correa \u2013 Barueri<\/p>\n<p>6\/9 \u2013 S\u00e3o Crist\u00f3v\u00e3o Sa\u00fade\/S\u00e3o Caetano 0 x 3\u00a0<strong>S\u00e3o Paulo F.C\/Barueri<\/strong>\u00a0(25-23, 25-23 e 29-27)<br \/>\nGin\u00e1sio Lauro Gomes \u2013 S\u00e3o Caetano do Sul<\/p>\n<p>17\/9 \u2013 Atacad\u00e3o Joseense 2 x 3\u00a0<strong>S\u00e3o Paulo F.C\/Barueri<\/strong>\u00a0(28-30, 25-19, 25-19, 23-25 e 15-10)<br \/>\nGin\u00e1sio Petrobras \u2013 S\u00e3o Jos\u00e9 dos Campos<\/p>\n<p>20\/9 \u2013\u00a0<strong>S\u00e3o Paulo F.C\/Barueri<\/strong>\u00a00 x 3 E.C Pinheiros (24-26, 21-25 e 18-25)<br \/>\nGin\u00e1sio Jos\u00e9 Correa \u2013 Barueri<\/p>\n<p>4\/10 \u2013\u00a0<strong>S\u00e3o Paulo F.C\/Barueri<\/strong>\u00a00 x 3 Sesi Bauru (15-25, 20-25 e 21-25)<br \/>\nGin\u00e1sio Jos\u00e9 Correa \u2013 Barueri<\/p>\n<p>11\/10 \u2013 Osasco Audax 3 x 0\u00a0<strong>S\u00e3o Paulo F.C\/Barueri\u00a0<\/strong>(25-23, 25-19 e 25-23)<br \/>\nGin\u00e1sio Jos\u00e9 Liberatti \u2013 Osasco<\/p>\n<p><strong>Quartas de final<\/strong><\/p>\n<p>22\/10 \u2013 S\u00e3o Crist\u00f3v\u00e3o Sa\u00fade\/S\u00e3o Caetano 0 x 3\u00a0<strong>S\u00e3o Paulo F.C\/Barueri\u00a0<\/strong>(22-25, 19-25 e 22-25)<strong><br \/>\n<\/strong>Gin\u00e1sio Lauro Gomes \u2013 S\u00e3o Caetano do Sul<\/p>\n<p>25\/10 \u2013\u00a0<strong>S\u00e3o Paulo F.C\/Barueri<\/strong>\u00a03 x 1 S\u00e3o Crist\u00f3v\u00e3o Sa\u00fade\/S\u00e3o Caetano (25-21, 25-21, 23-25 e 26-24)<br \/>\nGin\u00e1sio Jos\u00e9 Corr\u00eaa \u2013 Barueri<\/p>\n<p><strong>Semifinal<\/strong><\/p>\n<p>29\/10 \u2013\u00a0<strong>S\u00e3o Paulo F.C\/Barueri<\/strong>\u00a00 x 3 Sesi Bauru (23-25, 22-25 e 22-25)<br \/>\nGin\u00e1sio Jos\u00e9 Corr\u00eaa \u2013 Barueri<\/p>\n<p>2\/11 \u2013 Sesi Bauru 0 x 4 \u00a0<strong>S\u00e3o Paulo F.C\/Barueri<\/strong>\u00a0(19-25,19-25 e 20-25. Golden Set \u2013 16-25)<br \/>\nGin\u00e1sio Panela de Press\u00e3o &#8211; Bauru<\/p>\n<p><strong>O elenco do S\u00e3o Paulo F.C\/Barueri para a temporada 2019<\/strong><\/p>\n<p>#1 \u2013 Dani Terra \u2013 L\u00edbero \u2013 29\/7\/1994 \u2013 1,68 m \u2013 62 kg<br \/>\n#2 \u2013 Diana \u2013 Meio \u2013 22\/2\/1999 \u2013 1,91 m \u2013 65 kg<br \/>\n#3 \u2013 Juma \u2013 Levantadora \u2013 17\/1\/1993 \u2013 1,80 m \u2013 67 kg<br \/>\n#4 \u2013 Maira \u2013 Ponta \u2013 7\/3\/1995 \u2013 1,85 m \u2013 66 kg<br \/>\n#5\u00a0 &#8211; Thayane \u2013 Levantadora \u2013 12\/9\/2001 \u2013 1,78 m \u2013 60 kg<br \/>\n#6 \u2013 Nyeme \u2013 L\u00edbero \u2013 11\/10\/1998 \u2013 1,75 m \u2013 72 kg<br \/>\n#7 \u2013 Lays \u2013 Meio \u2013 13\/10\/1995 \u2013 1,85 m \u2013 71 kg<br \/>\n#8 \u2013 Jheovana \u2013 Ponteira\/Oposta \u2013 10\/1\/2001 \u2013 1,91 m \u2013 90 kg<br \/>\n#9 \u2013 Kisy \u2013 Oposta \u2013 28\/1\/2000 \u2013 1,89 m \u2013 75 kg<br \/>\n#10 \u2013 Tainara Santos \u2013 Ponteira \u2013 3\/3\/2000 \u2013 1,87 m \u2013 78 kg<br \/>\n#11 \u2013 Lorenne \u2013 Oposta \u2013 8\/1\/1996 \u2013 1,85 m \u2013 74 kg<br \/>\n#12 \u2013 Larissa \u2013 Meio \u2013 2\/3\/2001 \u2013 1,88 m \u2013 70 kg<br \/>\n#13 \u2013 Jacke \u2013 Levantadora \u2013 30\/12\/1999 \u2013 1,74 m \u2013 67 kg<br \/>\n#16 \u2013 Carol \u2013 Ponteira \u2013 28\/6\/2002 \u2013 1,92 m \u2013 78 kg<br \/>\n#18 \u2013 Mayany \u2013 Meio \u2013 24\/11\/1996 \u2013 1,85 m \u2013 62 kg<br \/>\n#19 \u2013 Parise \u2013 Ponteira \u2013 21\/3\/2002 \u2013 1,85 m \u2013 70 kg<\/p>\n<p>T\u00e9cnico: Jos\u00e9 Roberto Guimar\u00e3es<br \/>\nAuxiliares-t\u00e9cnicos: Wagner Coppini Fernandes, Alexandre Gomes e F\u00e1bio Rafael Simpl\u00edcio<br \/>\nPreparadores f\u00edsicos: Ca\u00edque Botelho e Eduardo Cianci Gomes<br \/>\nM\u00e9dico: J\u00falio C\u00e9sar Nardelli<br \/>\nFisioterapeutas: Fernando Alves Fernandes e Daniel Hideki Kan<br \/>\nEstat\u00edstico: F\u00e1bio Simpl\u00edcio e Luciano Tavares Lima<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tricolor supera o favorito Sesi Bauru duas vezes no Gin\u00e1sio Panela de Press\u00e3o e ir\u00e1 decidir o Estadual contra Osasco Audax ou Pinheiros O S\u00e3o Paulo F.C\/Barueri conquistou uma virada hist\u00f3rica e avan\u00e7ou para a final do Campeonato Paulista feminino de v\u00f4lei. Em um confronto que terminou na madrugada deste domingo (3), o Tricolor superou&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[110],"class_list":["post-2572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-voleifeminino-time-bvc-4life-hinode-saopaulofc-barueri"],"_links":{"self":[{"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/posts\/2572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/comments?post=2572"}],"version-history":[{"count":2,"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/posts\/2572\/revisions"}],"predecessor-version":[{"id":2574,"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/posts\/2572\/revisions\/2574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/media\/2494"}],"wp:attachment":[{"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/media?parent=2572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/categories?post=2572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bvc-volei.org\/site\/wp-json\/wp\/v2\/tags?post=2572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}